{"id":9149,"date":"2024-12-13T12:51:39","date_gmt":"2024-12-13T11:51:39","guid":{"rendered":"https:\/\/elcafedepipa.com\/?p=9149"},"modified":"2024-12-13T12:51:41","modified_gmt":"2024-12-13T11:51:41","slug":"matriarca-conquista-la-xii-edicio-del-festival-de-curtmetratges-cortometrando-de-la-diputacio-de-castello","status":"publish","type":"post","link":"https:\/\/elcafedepipa.com\/index.php\/2024\/12\/13\/matriarca-conquista-la-xii-edicio-del-festival-de-curtmetratges-cortometrando-de-la-diputacio-de-castello\/","title":{"rendered":"\u2018Matriarca\u2019 conquista la XII edici\u00f3 del Festival de Curtmetratges \u2018Cortometrando\u2019 de la Diputaci\u00f3 de Castell\u00f3."},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El curt \u2018Matriarca\u2019, de Guillermo Mart\u00ednez i Pablo P\u00e9rez, ha conquistat la XII edici\u00f3 del Festival de Curtmetratges \u2018Cortometrando\u2019 de la Diputaci\u00f3 de Castell\u00f3. El treball rodat a Fuentes de Ay\u00f3dar ha obtingut el suport del jurat en una gala en la qual s&#8217;ha reconegut l&#8217;esfor\u00e7 i l&#8217;excel\u00b7l\u00e8ncia d&#8217;aquells que, amb el seu treball, han destacat en esta edici\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aix\u00ed doncs, l&#8217;Auditori i Palau de Congressos de Castell\u00f3 s&#8217;ha vestit de gala per a celebrar la m\u00e0gia del cinema i l&#8217;art de contar hist\u00f2ries, i retre homenatge als cineastes que han format part de \u2018Cortometrando\u2019 2024. \u201cUna ocasi\u00f3 per a aplaudir la creativitat, l&#8217;enginy i l&#8217;esfor\u00e7 d&#8217;aquells que, a trav\u00e9s del seu treball, han aconseguit il\u00b7luminar amb la seua visi\u00f3 les tradicions, els paisatges i les emocions dels nostres pobles\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amb estes paraules, el diputat de Cultura de la instituci\u00f3 provincial, Alejandro Clausell, ha donat la benvinguda als nominats i nominades, al director del festival, Sergio Gonz\u00e1lez, aix\u00ed com als alcaldes, autoritats dels municipis en els quals s&#8217;ha rodat, que no s\u00f3n uns altres que La Jana, Geldo, Fuentes de Ay\u00f3dar, la Llosa i Sorita.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En este sentit, el diputat de Cultura ha posat en valor la import\u00e0ncia que t\u00e9 este festival per als municipis m\u00e9s xicotets de Castell\u00f3 i ha assegurat que \u00e9s una \u201cferramenta excepcional per a dinamitzar els pobles de l&#8217;interior i utilitzar el cinema com a vehicle de promoci\u00f3 tur\u00edstica\u201d. \u201cAll\u00ed, en eixos racons, s&#8217;encenen les llums de la creativitat, ens descobrixen el molt que tenen per a oferir i per aix\u00f2, esta celebraci\u00f3, ha de convertir-se en un reconeixement a la seua import\u00e0ncia\u201d, ha subratllat Clausell.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cadascun dels curts presentats en esta edici\u00f3 ha sigut exemple de com, amb un temps limitat, es poden aconseguir grans altures de creativitat i profunditat. Per\u00f2 m\u00e9s enll\u00e0 dels assoliments art\u00edstics, cadascun d&#8217;estos curtmetratges, tal com ha assenyalat el diputat \u201c\u00e9s tamb\u00e9 una finestra cap als nostres pobles\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al llarg d&#8217;este festival, que complix dotze anys, 70 dels 135 municipis de la prov\u00edncia han sigut escenari d&#8217;estos treballs, involucrant a ve\u00efns i ve\u00efnes, joves cineastes, i tota una comunitat que s&#8217;ha unit per a crear una petjada cinematogr\u00e0fica \u00fanica. \u201cEste \u00e9s, sens dubte, un dels grans assoliments d&#8217;este festival: la visibilitat dels nostres pobles i la seua capacitat per a inspirar noves generacions de creadors\u201d, ha ressaltat Clausell.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hist\u00f2ries originals en llocs especials<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La pe\u00e7a \u2018Matriarca\u2019 ha sigut la guanyadora d&#8217;esta edici\u00f3, mentres que el premi al Millor Actor, ha recaigut en David Collado pel seu enorme treball en este curtmetratge dirigit per Guillermo Mart\u00ednez i Pablo P\u00e9rez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El premi al Millor So ha sigut per a Pablo Ojeda, pel seu treball en el curtmetratge \u2018A la fresca\u2019, dirigit per Alexandra Croitoriu i rodat a Geldo. El premi a la millor fotografia ha sigut per a Paula Lorenzino, per la seua labor en este mateix curt, igual que el premi a la Millor Actriu, que en este cas ha recaigut en Lola Molt\u00f3, per la seua dedicaci\u00f3 i bona faena en \u2018A la fresca\u2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Finalment, el premi del P\u00fablico ha sigut per a \u2018Matriarca\u2019.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El diputat de Cultura, ha felicitat els nominats per la seua dedicaci\u00f3, per la seua creativitat i per la seua capacitat per a emocionar al p\u00fablic i als membres del jurat. \u201cEls premis que hem entregat s\u00f3n un reflex del talent i la passi\u00f3 que cadascun d&#8217;ells ha posat en els seus projectes\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El curt \u2018Matriarca\u2019, de Guillermo Mart\u00ednez i Pablo P\u00e9rez, ha conquistat la XII edici\u00f3 del Festival de Curtmetratges \u2018Cortometrando\u2019 de la Diputaci\u00f3 de Castell\u00f3. El treball rodat a Fuentes de Ay\u00f3dar ha obtingut el suport del jurat en una gala en la qual s&#8217;ha reconegut l&#8217;esfor\u00e7 i l&#8217;excel\u00b7l\u00e8ncia d&#8217;aquells que, amb el seu treball, han &#8230; <a title=\"\u2018Matriarca\u2019 conquista la XII edici\u00f3 del Festival de Curtmetratges \u2018Cortometrando\u2019 de la Diputaci\u00f3 de Castell\u00f3.\" class=\"read-more\" href=\"https:\/\/elcafedepipa.com\/index.php\/2024\/12\/13\/matriarca-conquista-la-xii-edicio-del-festival-de-curtmetratges-cortometrando-de-la-diputacio-de-castello\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre \u2018Matriarca\u2019 conquista la XII edici\u00f3 del Festival de Curtmetratges \u2018Cortometrando\u2019 de la Diputaci\u00f3 de Castell\u00f3.\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":9150,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"\u2018Matriarca\u2019 conquista la XII edici\u00f3 del Festival de Curtmetratges \u2018Cortometrando\u2019 de la Diputaci\u00f3 de Castell\u00f3. - El caf\u00e9 de Pipa","description":"El curt \u2018Matriarca\u2019, de Guillermo Mart\u00ednez i Pablo P\u00e9rez, ha conquistat la XII edici\u00f3 del Festival de Curtmetratges \u2018Cortometrando\u2019 de la Diputaci\u00f3 de Castell\u00f3."},"footnotes":""},"categories":[10],"tags":[],"ppma_author":[74],"class_list":["post-9149","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provinciadecastello"],"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El caf\u00e9 de Pipa","distributor_original_site_url":"https:\/\/elcafedepipa.com","push-errors":false,"authors":[{"term_id":74,"user_id":2,"is_guest":0,"slug":"radiolavallduixo","display_name":"Vicent Arnau Forner","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/26a27d13d194fc3b4d2a7a933a63466fa1af911ef6eac8a107691f6aeb82d442?s=96&d=mm&r=g","author_category":"","first_name":"ecdp","last_name":"","user_url":"http:\/\/www.elcafedepipa.com","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/9149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/comments?post=9149"}],"version-history":[{"count":0,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/9149\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media\/9150"}],"wp:attachment":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media?parent=9149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/categories?post=9149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/tags?post=9149"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/ppma_author?post=9149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}