{"id":26763,"date":"2026-07-17T13:30:00","date_gmt":"2026-07-17T11:30:00","guid":{"rendered":"https:\/\/elcafedepipa.com\/?p=26763"},"modified":"2026-07-17T12:49:38","modified_gmt":"2026-07-17T10:49:38","slug":"podcast-herminio-serra-repassa-lactualitat-de-la-vall-i-anuncia-les-ajudes-del-consell-per-a-la-climatitzacio-dels-centres-escolars","status":"publish","type":"post","link":"https:\/\/elcafedepipa.com\/index.php\/2026\/07\/17\/podcast-herminio-serra-repassa-lactualitat-de-la-vall-i-anuncia-les-ajudes-del-consell-per-a-la-climatitzacio-dels-centres-escolars\/","title":{"rendered":"Podcast | Herminio Serra repassa l&#8217;actualitat de la Vall i anuncia les ajudes del Consell per a la climatitzaci\u00f3 dels centres escolars."},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/elcafedepipa.com\/wp-content\/uploads\/2026\/07\/herminio17juliol.mp3\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":26764,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Podcast | Herminio Serra repassa l'actualitat de la Vall i anuncia les ajudes del Consell per a la climatitzaci\u00f3 dels centres escolars. - El caf\u00e9 de Pipa","description":""},"footnotes":""},"categories":[1],"tags":[],"ppma_author":[74],"class_list":["post-26763","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El caf\u00e9 de Pipa","distributor_original_site_url":"https:\/\/elcafedepipa.com","push-errors":false,"authors":[{"term_id":74,"user_id":2,"is_guest":0,"slug":"radiolavallduixo","display_name":"Vicent Arnau Forner","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/26a27d13d194fc3b4d2a7a933a63466fa1af911ef6eac8a107691f6aeb82d442?s=96&d=mm&r=g","author_category":"","first_name":"ecdp","last_name":"","user_url":"http:\/\/www.elcafedepipa.com","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/26763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/comments?post=26763"}],"version-history":[{"count":1,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/26763\/revisions"}],"predecessor-version":[{"id":26766,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/26763\/revisions\/26766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media\/26764"}],"wp:attachment":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media?parent=26763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/categories?post=26763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/tags?post=26763"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/ppma_author?post=26763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}