{"id":2352,"date":"2024-06-26T12:27:42","date_gmt":"2024-06-26T10:27:42","guid":{"rendered":"https:\/\/elcafedepipa.com\/?p=2352"},"modified":"2024-06-26T12:27:44","modified_gmt":"2024-06-26T10:27:44","slug":"la-policia-local-dalmenara-sorpren-in-fraganti-a-dos-lladres-de-melons-gracies-als-vols-de-vigilancia-del-dron","status":"publish","type":"post","link":"https:\/\/elcafedepipa.com\/index.php\/2024\/06\/26\/la-policia-local-dalmenara-sorpren-in-fraganti-a-dos-lladres-de-melons-gracies-als-vols-de-vigilancia-del-dron\/","title":{"rendered":"La Policia Local d&#8217;Almenara sorpr\u00e9n &#8220;in fraganti&#8221; a dos lladres de melons gr\u00e0cies als vols de vigil\u00e0ncia del dron"},"content":{"rendered":"\n<p style=\"font-size:24px\"><strong>Tamb\u00e9 va participar en les tasques de rescat d&#8217;un agricultor accidentat en caure-li un dep\u00f2sit damunt<\/strong><\/p>\n\n\n\n<p>Ahir, la Policia Local d&#8217;Almenara va sorprendre &#8220;in fraganti&#8221; a dues persones furtant melons en un camp del terme municipal gr\u00e0cies als vols amb dron que reforcen la vigil\u00e0ncia. Les persones detingudes han passat a disposici\u00f3 judicial. Segons el cap de la Policia Local, Javier Navarro, es van detectar a dues persones agafant melons durant un vol de vigil\u00e0ncia amb el dron. Es calcula que havien recol\u00b7lectat entre 400 i 500 kg de melons en el moment de ser atrapades.<\/p>\n\n\n\n<p>Aquests vols de dron per part de la Policia Local d&#8217;Almenara tamb\u00e9 serveixen per a la detecci\u00f3 de robatoris de collites i la localitzaci\u00f3 d&#8217;abocaments incontrolats.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" style=\"font-size:23px\"><strong>Rescat d&#8217;un Agricultor Accidentat<\/strong><\/h3>\n\n\n\n<p>D&#8217;altra banda, la Policia Local d&#8217;Almenara va participar en el rescat d&#8217;un agricultor accidentat al Cam\u00ed Bovar, a qui li va caure un dep\u00f2sit damunt. Un altre agricultor va sentir la petici\u00f3 d&#8217;ajuda i va telefonar a la Policia Local, la qual cosa va permetre activar l&#8217;operatiu de rescat, incloent la crida al SAMU. L&#8217;agricultor, que presentava diverses lesions, va ser traslladat a un centre hospitalari.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tamb\u00e9 va participar en les tasques de rescat d&#8217;un agricultor accidentat en caure-li un dep\u00f2sit damunt Ahir, la Policia Local d&#8217;Almenara va sorprendre &#8220;in fraganti&#8221; a dues persones furtant melons en un camp del terme municipal gr\u00e0cies als vols amb dron que reforcen la vigil\u00e0ncia. Les persones detingudes han passat a disposici\u00f3 judicial. Segons el &#8230; <a title=\"La Policia Local d&#8217;Almenara sorpr\u00e9n &#8220;in fraganti&#8221; a dos lladres de melons gr\u00e0cies als vols de vigil\u00e0ncia del dron\" class=\"read-more\" href=\"https:\/\/elcafedepipa.com\/index.php\/2024\/06\/26\/la-policia-local-dalmenara-sorpren-in-fraganti-a-dos-lladres-de-melons-gracies-als-vols-de-vigilancia-del-dron\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre La Policia Local d&#8217;Almenara sorpr\u00e9n &#8220;in fraganti&#8221; a dos lladres de melons gr\u00e0cies als vols de vigil\u00e0ncia del dron\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-2352","post","type-post","status-publish","format-standard","hentry","category-almenara"],"_links":{"self":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/2352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/comments?post=2352"}],"version-history":[{"count":0,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/2352\/revisions"}],"wp:attachment":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media?parent=2352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/categories?post=2352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/tags?post=2352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}