{"id":22256,"date":"2026-02-26T14:08:52","date_gmt":"2026-02-26T13:08:52","guid":{"rendered":"https:\/\/elcafedepipa.com\/?p=22256"},"modified":"2026-02-26T14:08:53","modified_gmt":"2026-02-26T13:08:53","slug":"podcast-repas-setmanal-baix-loptica-del-equip-de-govern-fernando-daros-4","status":"publish","type":"post","link":"https:\/\/elcafedepipa.com\/index.php\/2026\/02\/26\/podcast-repas-setmanal-baix-loptica-del-equip-de-govern-fernando-daros-4\/","title":{"rendered":"Podcast | Rep\u00e0s setmanal baix l&#8217;\u00f2ptica del equip de govern. Fernando Dar\u00f3s"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/elcafedepipa.com\/wp-content\/uploads\/2026\/02\/repas26feb.mp3\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":22257,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Podcast | Rep\u00e0s setmanal baix l'\u00f2ptica del equip de govern. Fernando Dar\u00f3s - El caf\u00e9 de Pipa","description":""},"footnotes":""},"categories":[34],"tags":[],"ppma_author":[74],"class_list":["post-22256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast"],"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El caf\u00e9 de Pipa","distributor_original_site_url":"https:\/\/elcafedepipa.com","push-errors":false,"authors":[{"term_id":74,"user_id":2,"is_guest":0,"slug":"radiolavallduixo","display_name":"Vicent Arnau Forner","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/26a27d13d194fc3b4d2a7a933a63466fa1af911ef6eac8a107691f6aeb82d442?s=96&d=mm&r=g","author_category":"","first_name":"ecdp","last_name":"","user_url":"http:\/\/www.elcafedepipa.com","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/22256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/comments?post=22256"}],"version-history":[{"count":1,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/22256\/revisions"}],"predecessor-version":[{"id":22267,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/22256\/revisions\/22267"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media\/22257"}],"wp:attachment":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media?parent=22256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/categories?post=22256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/tags?post=22256"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/ppma_author?post=22256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}