{"id":22212,"date":"2026-02-25T14:09:27","date_gmt":"2026-02-25T13:09:27","guid":{"rendered":"https:\/\/elcafedepipa.com\/?p=22212"},"modified":"2026-02-25T14:09:38","modified_gmt":"2026-02-25T13:09:38","slug":"podcast-larquet-ecologistes-en-accio-balenes-i-novetats-de-la-macroplanta-de-cellulosa-en-galicia","status":"publish","type":"post","link":"https:\/\/elcafedepipa.com\/index.php\/2026\/02\/25\/podcast-larquet-ecologistes-en-accio-balenes-i-novetats-de-la-macroplanta-de-cellulosa-en-galicia\/","title":{"rendered":"Podcast | L&#8217;arquet-ecologistes en acci\u00f3. Balenes i novetats de la macroplanta de cel\u00b7lulosa en Galicia"},"content":{"rendered":"\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/elcafedepipa.com\/wp-content\/uploads\/2026\/02\/arquet25febrer.mp3\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":22215,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"slim_seo":{"title":"Podcast | L'arquet-ecologistes en acci\u00f3. Balenes i novetats de la macroplanta de cel\u00b7lulosa en Galicia - El caf\u00e9 de Pipa","description":""},"footnotes":""},"categories":[34],"tags":[],"ppma_author":[74],"class_list":["post-22212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-podcast"],"distributor_meta":false,"distributor_terms":false,"distributor_media":false,"distributor_original_site_name":"El caf\u00e9 de Pipa","distributor_original_site_url":"https:\/\/elcafedepipa.com","push-errors":false,"authors":[{"term_id":74,"user_id":2,"is_guest":0,"slug":"radiolavallduixo","display_name":"Vicent Arnau Forner","avatar_url":"https:\/\/secure.gravatar.com\/avatar\/26a27d13d194fc3b4d2a7a933a63466fa1af911ef6eac8a107691f6aeb82d442?s=96&d=mm&r=g","author_category":"","first_name":"ecdp","last_name":"","user_url":"http:\/\/www.elcafedepipa.com","job_title":"","description":""}],"_links":{"self":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/22212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/comments?post=22212"}],"version-history":[{"count":1,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/22212\/revisions"}],"predecessor-version":[{"id":22224,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/22212\/revisions\/22224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media\/22215"}],"wp:attachment":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media?parent=22212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/categories?post=22212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/tags?post=22212"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/ppma_author?post=22212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}