{"id":2207,"date":"2024-06-21T12:44:00","date_gmt":"2024-06-21T10:44:00","guid":{"rendered":"https:\/\/elcafedepipa.com\/?p=2207"},"modified":"2024-06-21T12:44:48","modified_gmt":"2024-06-21T10:44:48","slug":"podcast-amparo-falco-tecnica-dimmigracio-i-jorge-marques-regidor-de-serveis-socials-amb-motiu-del-dia-internacional-de-las-personas-refugiades","status":"publish","type":"post","link":"https:\/\/elcafedepipa.com\/index.php\/2024\/06\/21\/podcast-amparo-falco-tecnica-dimmigracio-i-jorge-marques-regidor-de-serveis-socials-amb-motiu-del-dia-internacional-de-las-personas-refugiades\/","title":{"rendered":"Podcast | La Vall d&#8217;Uix\u00f3 commemora el Dia\u00a0Internacional de les\u00a0Persones Refugiades"},"content":{"rendered":"\n<p><strong>\u00c0UDIO | <\/strong>En\u00a0commemoraci\u00f3\u00a0del Dia Internacional de les Persones Refugiades celebrat ahir, Amparo Falc\u00f3,\u00a0t\u00e8cnica\u00a0d&#8217;immigraci\u00f3\u00a0i Jorge Marqu\u00e9s, regidor de Serveis Socials a la Vall d&#8217;Uix\u00f3 ens parlen de la import\u00e0ncia\u00a0de conscienciar a la ciutadania de la situaci\u00f3 que les persones refugiades pateixen, aix\u00ed com de la necessitat de la societat d\u2019acollir-los en les mans obertes i amb facilitats. Tamb\u00e9 hi participa en aquesta entrevista una refugiada amb asil a\u00a0la\u00a0Vall per a manifestar la seua\u00a0experi\u00e8ncia personal.<\/p>\n\n\n\n<figure class=\"wp-block-audio\"><audio controls src=\"https:\/\/elcafedepipa.com\/wp-content\/uploads\/2024\/06\/marques21juny.mp3\"><\/audio><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0UDIO | En\u00a0commemoraci\u00f3\u00a0del Dia Internacional de les Persones Refugiades celebrat ahir, Amparo Falc\u00f3,\u00a0t\u00e8cnica\u00a0d&#8217;immigraci\u00f3\u00a0i Jorge Marqu\u00e9s, regidor de Serveis Socials a la Vall d&#8217;Uix\u00f3 ens parlen de la import\u00e0ncia\u00a0de conscienciar a la ciutadania de la situaci\u00f3 que les persones refugiades pateixen, aix\u00ed com de la necessitat de la societat d\u2019acollir-los en les mans obertes i amb &#8230; <a title=\"Podcast | La Vall d&#8217;Uix\u00f3 commemora el Dia\u00a0Internacional de les\u00a0Persones Refugiades\" class=\"read-more\" href=\"https:\/\/elcafedepipa.com\/index.php\/2024\/06\/21\/podcast-amparo-falco-tecnica-dimmigracio-i-jorge-marques-regidor-de-serveis-socials-amb-motiu-del-dia-internacional-de-las-personas-refugiades\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre Podcast | La Vall d&#8217;Uix\u00f3 commemora el Dia\u00a0Internacional de les\u00a0Persones Refugiades\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[2,34],"tags":[],"class_list":["post-2207","post","type-post","status-publish","format-standard","hentry","category-lavallduixo","category-podcast"],"_links":{"self":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/2207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/comments?post=2207"}],"version-history":[{"count":0,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/2207\/revisions"}],"wp:attachment":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media?parent=2207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/categories?post=2207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/tags?post=2207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}