{"id":10182,"date":"2025-01-26T15:51:08","date_gmt":"2025-01-26T14:51:08","guid":{"rendered":"https:\/\/elcafedepipa.com\/?p=10182"},"modified":"2025-01-26T15:52:26","modified_gmt":"2025-01-26T14:52:26","slug":"exit-de-participacio-en-el-sant-antoni-matinal-de-2025","status":"publish","type":"post","link":"https:\/\/elcafedepipa.com\/index.php\/2025\/01\/26\/exit-de-participacio-en-el-sant-antoni-matinal-de-2025\/","title":{"rendered":"\u00c8xit de participaci\u00f3 en el Sant Antoni &#8220;matinal&#8221; de 2025 en la Vall d&#8217;Uix\u00f3"},"content":{"rendered":"\n<p>La cavalcada i encesa del pi de Sant Antoni passava aquest any 2025 al mat\u00ed, i possiblement arriba per a quedar-se en este horari perqu\u00e8 l&#8217;organitzaci\u00f3 s&#8217;ha mostrat molt satisfeta per l&#8217;alta participaci\u00f3. No era fins passades les dotze de migdia quan arrancava la cavalcada que ha recorregut l&#8217;itinerari de costum fins tornar de nou a la Pla\u00e7a de l&#8217;Assumpci\u00f3 on ha tingut lloc la benedicci\u00f3 dels animalets i l&#8217;entrega del tradicional rotllet de Sant Antoni. <\/p>\n\n\n\n<p>El que s\u00ed ha sigut diferent enguany \u00e9s el recorregut que ahir dissabte feia el pi degut a les obres de la Torre de Benissahat al carrer Assumpci\u00f3, i que tamb\u00e9 ha estat valorat com a possitiu tant per l&#8217;organitzaci\u00f3 com per els participants. <\/p>\n\n\n\n<p>All\u00f2 que el p\u00ed no es creme no se sap ben b\u00e9 si ja forma part de la tradici\u00f3 o perqu\u00e8 ha de ser de veres que \u00e9s una cosa complicada d&#8217;aconseguir. Sant Antoni 2026 ja espera.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"815\" height=\"1024\" src=\"https:\/\/elcafedepipa.com\/wp-content\/uploads\/2025\/01\/santantoni2-815x1024.jpeg\" alt=\"\" class=\"wp-image-10184\" srcset=\"https:\/\/elcafedepipa.com\/wp-content\/uploads\/2025\/01\/santantoni2-815x1024.jpeg 815w, https:\/\/elcafedepipa.com\/wp-content\/uploads\/2025\/01\/santantoni2-239x300.jpeg 239w, https:\/\/elcafedepipa.com\/wp-content\/uploads\/2025\/01\/santantoni2-768x966.jpeg 768w, https:\/\/elcafedepipa.com\/wp-content\/uploads\/2025\/01\/santantoni2-1222x1536.jpeg 1222w, https:\/\/elcafedepipa.com\/wp-content\/uploads\/2025\/01\/santantoni2.jpeg 1536w\" sizes=\"(max-width: 815px) 100vw, 815px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>La cavalcada i encesa del pi de Sant Antoni passava aquest any 2025 al mat\u00ed, i possiblement arriba per a quedar-se en este horari perqu\u00e8 l&#8217;organitzaci\u00f3 s&#8217;ha mostrat molt satisfeta per l&#8217;alta participaci\u00f3. No era fins passades les dotze de migdia quan arrancava la cavalcada que ha recorregut l&#8217;itinerari de costum fins tornar de nou &#8230; <a title=\"\u00c8xit de participaci\u00f3 en el Sant Antoni &#8220;matinal&#8221; de 2025 en la Vall d&#8217;Uix\u00f3\" class=\"read-more\" href=\"https:\/\/elcafedepipa.com\/index.php\/2025\/01\/26\/exit-de-participacio-en-el-sant-antoni-matinal-de-2025\/\" aria-label=\"M\u00e9s informaci\u00f3 sobre \u00c8xit de participaci\u00f3 en el Sant Antoni &#8220;matinal&#8221; de 2025 en la Vall d&#8217;Uix\u00f3\">Read more<\/a><\/p>\n","protected":false},"author":2,"featured_media":10183,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10182","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/10182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/comments?post=10182"}],"version-history":[{"count":0,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/posts\/10182\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media\/10183"}],"wp:attachment":[{"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/media?parent=10182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/categories?post=10182"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcafedepipa.com\/index.php\/wp-json\/wp\/v2\/tags?post=10182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}